{"id":4704,"date":"2024-10-20T20:42:31","date_gmt":"2024-10-20T20:42:31","guid":{"rendered":"https:\/\/aircraftrecovery.com\/?page_id=4704"},"modified":"2024-10-21T19:59:13","modified_gmt":"2024-10-21T19:59:13","slug":"resources-2","status":"publish","type":"page","link":"https:\/\/aircraftrecovery.com\/it\/resources-2\/","title":{"rendered":"Risorse"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4704\" class=\"elementor elementor-4704\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dbe505 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6dbe505\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a094846\" data-id=\"a094846\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09805d8 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"09805d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;prev_next&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5356 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/kenya-airports-authority-partners-with-ams-to-expand-aircraft-recovery-capabilities\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1284\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-scaled.jpg\" class=\"attachment-full size-full wp-image-5358\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-scaled.jpg 2560w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-300x151.jpg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-1024x514.jpg 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-768x385.jpg 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-1536x771.jpg 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-2048x1028.jpg 2048w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Ribbon_Cutting-18x9.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Notizie<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/kenya-airports-authority-partners-with-ams-to-expand-aircraft-recovery-capabilities\/\" >\n\t\t\t\tL'Autorit\u00e0 aeroportuale del Kenya collabora con AMS per ampliare le capacit\u00e0 di recupero degli aeromobili\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>L'Autorit\u00e0 Aeroportuale del Kenya collabora con AMS per ampliare le capacit\u00e0 di recupero degli aeromobili L'Autorit\u00e0 Aeroportuale del Kenya (KAA) e AMS Aircraft Recovery, Ltd (Regno Unito) sono lieti di annunciare il completamento di un importante investimento in tecnologia e attrezzature per il recupero degli aeromobili. Questo fondamentale<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/kenya-airports-authority-partners-with-ams-to-expand-aircraft-recovery-capabilities\/\" aria-label=\"Leggi tutto Kenya Airports Authority collabora con AMS per ampliare le capacit\u00e0 di recupero degli aeromobili\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5279 post type-post status-publish format-standard has-post-thumbnail hentry category-whitepaper\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/taxi\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1158\" height=\"811\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CASESTUDY-THUMBNAIL_Page_1.png\" class=\"attachment-full size-full wp-image-5257\" alt=\"Libro bianco in omaggio. recupero dell&#039;escursione della via di rullaggio a luton london\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CASESTUDY-THUMBNAIL_Page_1.png 1158w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CASESTUDY-THUMBNAIL_Page_1-300x210.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CASESTUDY-THUMBNAIL_Page_1-1024x717.png 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CASESTUDY-THUMBNAIL_Page_1-768x538.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CASESTUDY-THUMBNAIL_Page_1-18x12.png 18w\" sizes=\"(max-width: 1158px) 100vw, 1158px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Libro bianco<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/taxi\/\" >\n\t\t\t\tRECUPERO DELL'ESCURSIONE DELLA VIA DI RULLAGGIO A LUTON LONDRA\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Libro bianco gratuito Recupero dell'escursione della via di rullaggio a Luton Londra Analizziamo la risposta a un'escursione minore della via di rullaggio e analizziamo la tempistica del recupero. Inviami il libro bianco via e-mail<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/taxi\/\" aria-label=\"Leggi tutto TAXIWAY RECUPERO ESCURSIONI A LUTON LONDRA\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5164 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-resources category-tools\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/arm-quick-guide\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/12\/aircraft-lifting-airbags-2.jpg\" class=\"attachment-full size-full wp-image-776\" alt=\"airbag per il sollevamento degli aerei\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/12\/aircraft-lifting-airbags-2.jpg 1000w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/12\/aircraft-lifting-airbags-2-300x200.jpg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/12\/aircraft-lifting-airbags-2-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/arm-quick-guide\/\" >\n\t\t\t\tGuida rapida al capitolo ARM\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Guida rapida ai capitoli ARM Scarica la Guida rapida ai capitoli del manuale di recupero degli aeromobili AMS - Una guida di riferimento rapida per trovare le informazioni chiave sul recupero per tipo di AC nel relativo manuale. Scarica il PDF<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/arm-quick-guide\/\" aria-label=\"Leggi tutto Guida rapida al capitolo ARM\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4980 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-aircraft-towing category-commercial category-mil category-news category-resources\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/introducing-ams-aircraft-recovery-dolly\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4949\" alt=\"Immagine del carrello di recupero AMS per tutti i tipi di aeromobili\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-scaled.jpg 2560w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-300x225.jpg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-1024x768.jpg 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-768x576.jpg 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-1536x1152.jpg 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-2048x1536.jpg 2048w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/IMG_3208-1-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/introducing-ams-aircraft-recovery-dolly\/\" >\n\t\t\t\tCarrello di recupero per aeromobili - Capacit\u00e0 di 38 tonnellate\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>AMS annuncia il nuovo carrello di recupero aeromobili da 38 tonnellate. Il carrello di recupero AMS \u00e8 uno strumento autonomo che consente agli aeroporti e agli operatori di liberare le piste senza ritardi, riducendo al minimo i danni secondari all'aeromobile o alla pista.<\/p>\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/introducing-ams-aircraft-recovery-dolly\/\" aria-label=\"Leggi tutto Aircraft Recovery Dolly - Capacit\u00e0 di 38 tonnellate\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4869 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-aircraft-recovery-training category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/training-schedule\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-3.jpg\" class=\"attachment-full size-full wp-image-3435\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-3.jpg 1600w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-3-300x225.jpg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-3-1024x768.jpg 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-3-768x576.jpg 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-3-1536x1152.jpg 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-3-16x12.jpg 16w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/training-schedule\/\" >\n\t\t\t\tAMS Aircraft Recovery annuncia il programma di formazione\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>AMS \u00e8 lieta di annunciare le nuove date del prossimo corso pratico di recupero aeromobili presso il Cotswold Airport Training Centre. Questi corsi offrono ad aeroporti, compagnie aeree e altri soggetti interessati una preziosa esperienza pratica e una formazione teorica completa.<\/p>\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/training-schedule\/\" aria-label=\"Leggi tutto AMS Aircraft Recovery annuncia il programma di formazione\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5060 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-aircraft-recovery-training category-aircraft-towing category-aircraft-transport category-mil category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/experts-in-disabled-aircraft-recovery-from-five-allied-nations-gathered-at-woensdrecht-air-base-in-the-netherlands-in-october-to-evaluate-a-new-fighter-aircraft-recovery-transporter-system-introduced\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"521\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Recovery-Transporter-24-website.jpeg\" class=\"attachment-full size-full wp-image-5061\" alt=\"Gli esperti di recupero di velivoli disabili di cinque nazioni alleate si sono riuniti in ottobre presso la base aerea di Woensdrecht, nei Paesi Bassi, per valutare un nuovo sistema di trasporto per velivoli da combattimento introdotto da AMS Aircraft Recovery.\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Recovery-Transporter-24-website.jpeg 1200w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Recovery-Transporter-24-website-300x130.jpeg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Recovery-Transporter-24-website-1024x445.jpeg 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Recovery-Transporter-24-website-768x333.jpeg 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Recovery-Transporter-24-website-18x8.jpeg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/experts-in-disabled-aircraft-recovery-from-five-allied-nations-gathered-at-woensdrecht-air-base-in-the-netherlands-in-october-to-evaluate-a-new-fighter-aircraft-recovery-transporter-system-introduced\/\" >\n\t\t\t\tAMS dimostra agli alleati europei un innovativo caccia-trasportatore\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Esperti di recupero di velivoli disabili provenienti da cinque nazioni alleate si sono riuniti in ottobre presso la base aerea di Woensdrecht, nei Paesi Bassi, per valutare un nuovo sistema di trasporto per velivoli da combattimento introdotto da AMS Aircraft Recovery. Il nuovo sistema \u00e8 stato sviluppato su richiesta dell'F-35 Joint Program Office di Hill AFB.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/experts-in-disabled-aircraft-recovery-from-five-allied-nations-gathered-at-woensdrecht-air-base-in-the-netherlands-in-october-to-evaluate-a-new-fighter-aircraft-recovery-transporter-system-introduced\/\" aria-label=\"Leggi tutto AMS dimostra l&#039;innovativo Fighter Transporter con gli alleati europei\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4926 post type-post status-publish format-standard has-post-thumbnail hentry category-tools\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/quick-guide-to-airbag-heights-under-aircraft\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1592\" height=\"650\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-11-19-at-2.57.47 PM.png\" class=\"attachment-full size-full wp-image-4928\" alt=\"GUIDA RAPIDA ALLE ALTEZZE DEGLI AIRBAG SOTTO GLI AEROMOBILI Immagine\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-11-19-at-2.57.47\u202fPM.png 1592w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-11-19-at-2.57.47\u202fPM-300x122.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-11-19-at-2.57.47\u202fPM-1024x418.png 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-11-19-at-2.57.47\u202fPM-768x314.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-11-19-at-2.57.47\u202fPM-1536x627.png 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-11-19-at-2.57.47\u202fPM-18x7.png 18w\" sizes=\"(max-width: 1592px) 100vw, 1592px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Strumenti<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/quick-guide-to-airbag-heights-under-aircraft\/\" >\n\t\t\t\tGUIDA RAPIDA ALLE ALTEZZE DEGLI AIRBAG SOTTO GLI AEREI\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>GUIDA RAPIDA ALLE ALTEZZE DEGLI AIRBAG SOTTO GLI AEROMOBILI Scarica la Guida rapida AMS alle altezze degli airbag sotto gli aerei - Una guida di riferimento rapida per determinare le altezze e i carichi degli airbag in base al tipo e alla posizione degli AC. Scaricare il PDF<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/quick-guide-to-airbag-heights-under-aircraft\/\" aria-label=\"Leggi tutto GUIDA RAPIDA ALLE ALTEZZE DEGLI AIRBAG SOTTO GLI AEROMOBILI\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4893 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/f-35-joint-program-office-hosts-first-ever-international-crash-recovery-training-featuring-ams-recovery-equipment\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1200\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CDDAR-Training-1.jpg\" class=\"attachment-full size-full wp-image-4911\" alt=\"Immagine dell&#039;addestramento al recupero di aerei con il trasporto di recupero di aerei da combattimento AMS\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CDDAR-Training-1.jpg 1800w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CDDAR-Training-1-300x200.jpg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CDDAR-Training-1-1024x683.jpg 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CDDAR-Training-1-768x512.jpg 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CDDAR-Training-1-1536x1024.jpg 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/CDDAR-Training-1-18x12.jpg 18w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/f-35-joint-program-office-hosts-first-ever-international-crash-recovery-training-featuring-ams-recovery-equipment\/\" >\n\t\t\t\tL'Ufficio del programma congiunto F-35 ospita il primo addestramento internazionale per il recupero degli incidenti con l'attrezzatura di recupero AMS.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>L'Ufficio di programma congiunto F-35 dell'Aeronautica Militare degli Stati Uniti ha recentemente ospitato il primo corso globale di recupero di velivoli danneggiati o disabilitati (CDDAR) a Volk Field. Dall'8 al 14 settembre 2024, oltre 100 esperti di recupero provenienti da tutto il mondo, tra cui rappresentanti dell'Aeronautica, della Marina, del Corpo dei Marines e di altre forze armate, hanno partecipato al corso.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/f-35-joint-program-office-hosts-first-ever-international-crash-recovery-training-featuring-ams-recovery-equipment\/\" aria-label=\"Leggi tutto L&#039;Ufficio del programma congiunto F-35 ospita il primo addestramento internazionale per il recupero di un incidente con l&#039;attrezzatura di recupero AMS\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4853 post type-post status-publish format-standard has-post-thumbnail hentry category-lift category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/sky-high-with-skyhook-by-age-logistics\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"574\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-31-at-1.30.59 PM.png\" class=\"attachment-full size-full wp-image-4859\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-31-at-1.30.59\u202fPM.png 730w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-31-at-1.30.59\u202fPM-300x236.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-31-at-1.30.59\u202fPM-15x12.png 15w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Sollevamento di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/sky-high-with-skyhook-by-age-logistics\/\" >\n\t\t\t\tIn alto i cieli con Skyhook di AGE Logistics\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>AGE Logistics Corporation \u00e8 un produttore di apparecchiature originali con cui Thern, Inc. \u00e8 in affari da oltre un decennio. Per saperne di pi\u00f9 su come Thern e AGE collaborano per fornire attrezzature di alta qualit\u00e0 all'Aeronautica Militare degli Stati Uniti, leggete qui. Il produttore di apparecchiature originali: Analogamente a Thern, Inc., AGE Logistics<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/sky-high-with-skyhook-by-age-logistics\/\" aria-label=\"Leggi tutto Sky High con Skyhook di AGE Logistics\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4730 post type-post status-publish format-standard has-post-thumbnail hentry category-whitepaper\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/collaboration-is-key-whitepaper\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1131\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS762_White-Paper-Collaboration_v3_Page_1-e1729555541289.jpg\" class=\"attachment-full size-full wp-image-4742\" alt=\"\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Libro bianco<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/collaboration-is-key-whitepaper\/\" >\n\t\t\t\tRECUPERO DEGLI AEROMOBILI: LA COLLABORAZIONE \u00c8 FONDAMENTALE\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Libro bianco gratuito RECUPERO DI AEROMOBILI - LA COLLABORAZIONE \u00c8 LA CHIAVE Inviami il libro bianco via e-mail<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/collaboration-is-key-whitepaper\/\" aria-label=\"Leggi tutto RECUPERO AERONAUTICO - LA COLLABORAZIONE \u00c8 CHIAVE\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4693 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-aircraft-recovery-training category-video\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/air-national-guard-and-active-duty-airmen-have-what-it-takes-to-clear-their-runway-of-disabled-aircraft\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2270\" height=\"1272\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM.png\" class=\"attachment-full size-full wp-image-4702\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM.png 2270w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM-300x168.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM-1024x574.png 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM-768x430.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM-1536x861.png 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM-2048x1148.png 2048w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-5.08.08\u202fPM-18x10.png 18w\" sizes=\"(max-width: 2270px) 100vw, 2270px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/air-national-guard-and-active-duty-airmen-have-what-it-takes-to-clear-their-runway-of-disabled-aircraft\/\" >\n\t\t\t\tLa Guardia Nazionale Aerea e gli aviatori in servizio attivo hanno le carte in regola per liberare la pista dagli aerei in panne.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>HAWAII, STATI UNITI 14.01.2015 A Hickam Field, se un velivolo viene disabilitato all'atterraggio, una squadra di aviatori della Guardia Nazionale Aerea delle Hawaii e dell'Aeronautica Militare in servizio attivo interviene per liberare la pista e riaprire il campo di volo. La squadra CDDAR (Crashed Damaged or Disabled Aircraft Recovery)<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/air-national-guard-and-active-duty-airmen-have-what-it-takes-to-clear-their-runway-of-disabled-aircraft\/\" aria-label=\"Leggi tutto Gli aviatori della Guardia Nazionale Aerea e quelli in servizio attivo hanno le carte in regola per liberare le piste dagli aerei fuori uso.\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4680 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-transport category-news tag-transporter\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/f-35-jpo-trains-on-ams-fighter-recovery-transporter\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"838\" height=\"400\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/F35-training1-838x400-1.webp\" class=\"attachment-full size-full wp-image-4682\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/F35-training1-838x400-1.webp 838w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/F35-training1-838x400-1-300x143.webp 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/F35-training1-838x400-1-768x367.webp 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/F35-training1-838x400-1-18x9.webp 18w\" sizes=\"(max-width: 838px) 100vw, 838px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Trasporto aereo<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/f-35-jpo-trains-on-ams-fighter-recovery-transporter\/\" >\n\t\t\t\tL'F-35 JPO si addestra sul trasportatore di recupero dei caccia AMS\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>di Todd Cromar | Hill AFB, Utah - 13 ottobre 2022 Il 388\u00b0 Gruppo di Manutenzione della Hill Air Force Base, nello Utah, ha recentemente ospitato un corso di recupero di un F-35, primo nel suo genere, utilizzando un F-35A Lightning II appena ritirato e ora riassemblato. Il corso di recupero di cinque giorni dell'F-35 Joint Program Office per il recupero di un velivolo danneggiato o disabilitato da un incidente.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/f-35-jpo-trains-on-ams-fighter-recovery-transporter\/\" aria-label=\"Leggi tutto F-35 JPO si addestra sul trasportatore di recupero dei caccia AMS\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4364 post type-post status-publish format-standard has-post-thumbnail hentry category-lift category-aircraft-recovery category-commercial category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/lifting-the-worlds-largest-aircraft\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"164\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Nose-Gear-Failures.jpeg\" class=\"attachment-full size-full wp-image-4896\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Nose-Gear-Failures.jpeg 320w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Nose-Gear-Failures-300x154.jpeg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Nose-Gear-Failures-18x9.jpeg 18w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Sollevamento di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/lifting-the-worlds-largest-aircraft\/\" >\n\t\t\t\tAMS e Modulift festeggiano 17 anni di collaborazione\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Sollevare l'aereo pi\u00f9 grande del mondo posted by AJOT | Apr 30 2024 at 11:54 AM | Air Cargo Il primo sistema di sollevamento di Modulift ha segnato una nuova era nel settore aerospaziale commerciale e militare quando \u00e8 stato lanciato nel 2007 per AMS Aircraft Recovery. Quando un aeromobile si guasta deve essere sollevato - in modo sicuro<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/lifting-the-worlds-largest-aircraft\/\" aria-label=\"Leggi tutto AMS e Modulift festeggiano 17 anni di collaborazione\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3773 post type-post status-publish format-standard has-post-thumbnail hentry category-tools\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-recovery-load-calculator\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"462\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Zircraft-Lifting-Calculation.png\" class=\"attachment-full size-full wp-image-3662\" alt=\"Immagine della calcolatrice del carico di recupero degli aeromobili\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Zircraft-Lifting-Calculation.png 1280w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Zircraft-Lifting-Calculation-300x108.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Zircraft-Lifting-Calculation-1024x370.png 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Zircraft-Lifting-Calculation-768x277.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Zircraft-Lifting-Calculation-18x6.png 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Strumenti<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-recovery-load-calculator\/\" >\n\t\t\t\tCalcolo del carico di recupero dell'aeromobile\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>AMS Aircraft Recovery Load Calculator Per sollevare e spostare in sicurezza un aeromobile \u00e8 necessario conoscere i carichi nei punti di sollevamento. Il nostro strumento online gratuito AMS lo rende facile.  Utilizzate il calcolatore di carico<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-recovery-load-calculator\/\" aria-label=\"Leggi tutto Calcolo del carico di recupero dell&#039;aeromobile\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-995 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-aircraft-transport category-mil category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/recovery-transporter-for-military-light-aircraft\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-scaled.jpg\" class=\"attachment-full size-full wp-image-1450\" alt=\"Immagine del trasportatore per il recupero degli aerei AMS.\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-scaled.jpg 2560w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-300x225.jpg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-1024x768.jpg 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-768x576.jpg 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-1536x1152.jpg 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-2048x1536.jpg 2048w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2022\/01\/SCC-HS17-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/recovery-transporter-for-military-light-aircraft\/\" >\n\t\t\t\tAMS Aircraft Recovery presenta un nuovo trasportatore di recupero per velivoli da combattimento\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Nuovo Recovery Transporter per velivoli leggeri militari AMS presenta un nuovo Recovery Transporter che solleva e trasporta in scenari con superfici sia dure che morbide. Il Recovery Transporter \u00e8 stato convalidato per l'uso con F-35, F-16, F-22 e altri aerei da combattimento.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/recovery-transporter-for-military-light-aircraft\/\" aria-label=\"Leggi tutto AMS Aircraft Recovery presenta un nuovo trasportatore di recupero per velivoli da combattimento\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1 post type-post status-publish format-standard has-post-thumbnail hentry category-lift category-aircraft-recovery category-commercial category-news\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/new-over-wing-lift-owl-system\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"800\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/11\/test1.jpg\" class=\"attachment-full size-full wp-image-1214\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/11\/test1.jpg 1600w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/11\/test1-300x150.jpg 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/11\/test1-1024x512.jpg 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/11\/test1-768x384.jpg 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/2021\/11\/test1-1536x768.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Sollevamento di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/new-over-wing-lift-owl-system\/\" >\n\t\t\t\tAMS Aircraft Recovery presenta il nuovo sistema di sollevamento sopra l'ala (OWL\u00a9)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Nuovo sistema di attrezzi per il sollevamento dell'ala (OWL\u00a9) per facilitare il recupero rapido e sicuro di aeromobili con guasti al carrello. AMS presenta una soluzione innovativa per il sollevamento di aeromobili commerciali di grandi dimensioni in cui il sollevamento con airbag potrebbe non essere pratico. Mark Knight, direttore tecnico di AMS: \"La semplicit\u00e0 e il costo del sistema OWL Tooling di AMS<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/new-over-wing-lift-owl-system\/\" aria-label=\"Leggi tutto AMS Aircraft Recovery introduce il nuovo sistema di sollevamento sopra l&#039;ala (OWL\u00a9)\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2887 post type-post status-publish format-standard has-post-thumbnail hentry category-lift category-aircraft-recovery category-aircraft-transport category-commercial category-video\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/fuselage-lifting-system-turntable-by-ams-3\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"915\" height=\"416\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-10.26.09 AM.png\" class=\"attachment-full size-full wp-image-4675\" alt=\"\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-10.26.09\u202fAM.png 915w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-10.26.09\u202fAM-300x136.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-10.26.09\u202fAM-768x349.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2024-10-17-at-10.26.09\u202fAM-18x8.png 18w\" sizes=\"(max-width: 915px) 100vw, 915px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Sollevamento di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/fuselage-lifting-system-turntable-by-ams-3\/\" >\n\t\t\t\tSistema di sollevamento della fusoliera e piattaforma girevole di AMS\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Sistema di sollevamento della fusoliera e piattaforma girevole di AMS Sistema di sollevamento della fusoliera utilizzato per sollevare il muso di un aereo a reazione a fusoliera larga prima di calarlo su una piattaforma girevole da 50 tonnellate. Esercitazione condotta da AMS, specialista in attrezzature per il recupero di aeromobili e addestramento al recupero di aeromobili.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/fuselage-lifting-system-turntable-by-ams-3\/\" aria-label=\"Leggi tutto Sistema di sollevamento della fusoliera e tavola rotante di AMS\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3361 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-commercial category-video\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-lifting-and-recovery-demonstration-by-ams\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1884\" height=\"1058\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS_Aircraft_Lifting_2013-1.png\" class=\"attachment-full size-full wp-image-3364\" alt=\"Video sul sollevamento di aeromobili AMS Aircraft Recovery in tedesco\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS_Aircraft_Lifting_2013-1.png 1884w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS_Aircraft_Lifting_2013-1-300x168.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS_Aircraft_Lifting_2013-1-1024x575.png 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS_Aircraft_Lifting_2013-1-768x431.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS_Aircraft_Lifting_2013-1-1536x863.png 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS_Aircraft_Lifting_2013-1-18x10.png 18w\" sizes=\"(max-width: 1884px) 100vw, 1884px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-lifting-and-recovery-demonstration-by-ams\/\" >\n\t\t\t\tDimostrazione di sollevamento e recupero di un aeromobile da parte di AMS\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Sollevamento completo dell'aeromobile con airbag di sollevamento e movimento del trasportatore sull'aeromobile Trident 3 da parte di AMS, specialista nel recupero di aeromobili. Il video mostra la preparazione degli airbag e dell'attrezzatura di gonfiaggio prima del movimento dell'aereo. Gli airbag a elemento singolo da 30 tonnellate e gli airbag a elemento singolo da 15 tonnellate sono<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-lifting-and-recovery-demonstration-by-ams\/\" aria-label=\"Leggi tutto Dimostrazione di sollevamento e recupero di aeromobili da parte di AMS\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2849 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-aircraft-recovery-training category-video\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-recovery-equipment-training-exercise-by-ams-specialists-in-aircraft-recovery-training-and-aircraft-recovery-equipment\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1480\" height=\"904\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2023-01-08-at-4.13.14-PM.png\" class=\"attachment-full size-full wp-image-2854\" alt=\"Video di formazione sul recupero degli aeromobili AMS\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2023-01-08-at-4.13.14-PM.png 1480w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2023-01-08-at-4.13.14-PM-300x183.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2023-01-08-at-4.13.14-PM-1024x625.png 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2023-01-08-at-4.13.14-PM-768x469.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/Screenshot-2023-01-08-at-4.13.14-PM-18x12.png 18w\" sizes=\"(max-width: 1480px) 100vw, 1480px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-recovery-equipment-training-exercise-by-ams-specialists-in-aircraft-recovery-training-and-aircraft-recovery-equipment\/\" >\n\t\t\t\tFormazione sulle attrezzature di recupero da parte di AMS\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Il video mostra una delle esercitazioni pratiche di cui gli studenti beneficiano presso la struttura di formazione dedicata di AMS nel Regno Unito. In questo esempio, gli studenti utilizzano gli airbag per sollevare la fusoliera di un aeromobile B737 che \u00e8 stato allestito per rappresentare un guasto al carrello anteriore. <\/p>\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/aircraft-recovery-equipment-training-exercise-by-ams-specialists-in-aircraft-recovery-training-and-aircraft-recovery-equipment\/\" aria-label=\"Leggi tutto Formazione sulle attrezzature di recupero di AMS\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2461 post type-post status-publish format-standard has-post-thumbnail hentry category-aircraft-recovery category-commercial category-video\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/aircraftrecovery.com\/it\/sledge-recovery-video\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2670\" height=\"1552\" src=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video.png\" class=\"attachment-full size-full wp-image-2491\" alt=\"Video del sistema a slitta AMS\" srcset=\"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video.png 2670w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video-300x174.png 300w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video-1024x595.png 1024w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video-768x446.png 768w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video-1536x893.png 1536w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video-2048x1190.png 2048w, https:\/\/aircraftrecovery.com\/wp-content\/uploads\/AMS-Sledge-Video-18x10.png 18w\" sizes=\"(max-width: 2670px) 100vw, 2670px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Recupero di aeromobili<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/aircraftrecovery.com\/it\/sledge-recovery-video\/\" >\n\t\t\t\tSistema di movimentazione a slitta AMS per il recupero di aeromobili\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Sistema di movimento a slitta AMS per il recupero di un velivolo Questo video \u00e8 presentato da Jerry Paluszek, ingegnere capo della Boeing Company. Mostra il sistema di movimento a slitta di AMS per il recupero di un aereo che ha subito un guasto completo al carrello di atterraggio.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/aircraftrecovery.com\/it\/sledge-recovery-video\/\" aria-label=\"Leggi tutto AMS Sledge Movement System per il recupero degli aeromobili\" tabindex=\"-1\" >\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-4704","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resources - AMS Aircraft Recovery<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aircraftrecovery.com\/it\/resources-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resources\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aircraftrecovery.com\/it\/resources-2\/\" \/>\n<meta property=\"og:site_name\" content=\"AMS Aircraft Recovery\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-21T19:59:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/resources-2\\\/\",\"url\":\"https:\\\/\\\/aircraftrecovery.com\\\/resources-2\\\/\",\"name\":\"Resources - AMS Aircraft Recovery\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/#website\"},\"datePublished\":\"2024-10-20T20:42:31+00:00\",\"dateModified\":\"2024-10-21T19:59:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/resources-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aircraftrecovery.com\\\/resources-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/resources-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aircraftrecovery.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/\",\"name\":\"AMS Aircraft Recovery\",\"description\":\"LIFTING - TOWING - TRANSPORT - TRAINING\",\"publisher\":{\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/#organization\",\"name\":\"AMS Aircraft Recovery\",\"alternateName\":\"AGE Logistics Corporation\",\"url\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aircraftrecovery.com\\\/wp-content\\\/uploads\\\/cropped-AMS-icon-logo.png\",\"contentUrl\":\"https:\\\/\\\/aircraftrecovery.com\\\/wp-content\\\/uploads\\\/cropped-AMS-icon-logo.png\",\"width\":512,\"height\":512,\"caption\":\"AMS Aircraft Recovery\"},\"image\":{\"@id\":\"https:\\\/\\\/aircraftrecovery.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ams-aircraft-recovery\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Risorse - Recupero aeromobili AMS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aircraftrecovery.com\/it\/resources-2\/","og_locale":"it_IT","og_type":"article","og_title":"Resources","og_url":"https:\/\/aircraftrecovery.com\/it\/resources-2\/","og_site_name":"AMS Aircraft Recovery","article_modified_time":"2024-10-21T19:59:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aircraftrecovery.com\/resources-2\/","url":"https:\/\/aircraftrecovery.com\/resources-2\/","name":"Risorse - Recupero aeromobili AMS","isPartOf":{"@id":"https:\/\/aircraftrecovery.com\/de\/#website"},"datePublished":"2024-10-20T20:42:31+00:00","dateModified":"2024-10-21T19:59:13+00:00","breadcrumb":{"@id":"https:\/\/aircraftrecovery.com\/resources-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aircraftrecovery.com\/resources-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aircraftrecovery.com\/resources-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aircraftrecovery.com\/"},{"@type":"ListItem","position":2,"name":"Resources"}]},{"@type":"WebSite","@id":"https:\/\/aircraftrecovery.com\/de\/#website","url":"https:\/\/aircraftrecovery.com\/de\/","name":"AMS Recupero aeromobili","description":"SOLLEVAMENTO - TRAINO - TRASPORTO - FORMAZIONE","publisher":{"@id":"https:\/\/aircraftrecovery.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aircraftrecovery.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/aircraftrecovery.com\/de\/#organization","name":"AMS Recupero aeromobili","alternateName":"AGE Logistics Corporation","url":"https:\/\/aircraftrecovery.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aircraftrecovery.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/cropped-AMS-icon-logo.png","contentUrl":"https:\/\/aircraftrecovery.com\/wp-content\/uploads\/cropped-AMS-icon-logo.png","width":512,"height":512,"caption":"AMS Aircraft Recovery"},"image":{"@id":"https:\/\/aircraftrecovery.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/ams-aircraft-recovery\/"]}]}},"_links":{"self":[{"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/pages\/4704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/comments?post=4704"}],"version-history":[{"count":10,"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/pages\/4704\/revisions"}],"predecessor-version":[{"id":4766,"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/pages\/4704\/revisions\/4766"}],"wp:attachment":[{"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/media?parent=4704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/categories?post=4704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aircraftrecovery.com\/it\/wp-json\/wp\/v2\/tags?post=4704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}